{"id":3691,"date":"2020-12-19T00:00:09","date_gmt":"2020-12-18T23:00:09","guid":{"rendered":"https:\/\/forworld.redemptor.pl\/?p=3691"},"modified":"2020-12-18T18:57:28","modified_gmt":"2020-12-18T17:57:28","slug":"clamando-al-mesias-3-oh-renuevo-de-jese","status":"publish","type":"post","link":"https:\/\/forworld.redemptor.pl\/es\/clamando-al-mesias-3-oh-renuevo-de-jese\/","title":{"rendered":"Clamando al Mes\u00edas #3 &#8211; Oh, Renuevo de Jes\u00e9"},"content":{"rendered":"<p>\u00a1Saludos en Cristo! 19 de diciembre y una nueva Gran Ant\u00edfona de Adviento ante nosotros para reflexionar. Escuch\u00e9mosla de la voz del p. Tomasz Jarosz.<\/p>\n<p>La ant\u00edfona de hoy es una gran llamada al Mes\u00edas, el cual ha de venir y liberar al ser humano, y nos remite a dos fragmentos del Libro del profeta Isa\u00edas. En el cap\u00edtulo 11 podemos leer: \u201cSaldr\u00e1 un renuevo del tronco de Jes\u00e9, y un reto\u00f1o de sus ra\u00edces brotar\u00e1\u201d. \u00bfQui\u00e9n es Jes\u00e9? Jes\u00e9 es el padre del rey David. Este anuncio mesi\u00e1nico muestra, pues, que el futuro Mes\u00edas proceder\u00e1 del linaje real de David. Este rey que est\u00e1 por venir no ser\u00e1 s\u00f3lo el sucesor al trono dav\u00eddico, sino que ser\u00e1 un David nuevo, ideal, que comenzar\u00e1 el gobierno del Reino de Dios. A este ins\u00f3lito y excepcional nuevo rey lo presenta el mismo Isa\u00edas. Escuchemos c\u00f3mo lo describe el profeta, como presenta su reino: \u201cReposar\u00e1 sobre \u00e9l el esp\u00edritu de Yahveh: esp\u00edritu de sabidur\u00eda e inteligencia, esp\u00edritu de consejo y fortaleza, esp\u00edritu de ciencia y temor de Yahveh. Y le inspirar\u00e1 en el temor de Yahveh. No juzgar\u00e1 por las apariencias, ni sentenciar\u00e1 de o\u00eddas. Juzgar\u00e1 con justicia a los d\u00e9biles, y sentenciar\u00e1 con rectitud a los pobres de la tierra. Herir\u00e1 al hombre cruel con la vara de su boca, con el soplo de sus labios matar\u00e1 al malvado. Justicia ser\u00e1 el ce\u00f1idor de su cintura; verdad. el cintur\u00f3n de sus flancos. Ser\u00e1n vecinos el lobo y el cordero, y el leopardo se echar\u00e1 con el cabrito, el novillo y el cachorro pacer\u00e1n juntos, y un ni\u00f1o peque\u00f1o los conducir\u00e1. La vaca y la osa pacer\u00e1n, juntas acostar\u00e1n sus cr\u00edas, el le\u00f3n, como los bueyes, comer\u00e1 paja. Hurgar\u00e1 el ni\u00f1o de pecho en el agujero del \u00e1spid, y en la hura de la v\u00edbora el reci\u00e9n destetado meter\u00e1 la mano. Nadie har\u00e1 da\u00f1o, nadie har\u00e1 mal en todo mi santo Monte, porque la tierra estar\u00e1 llena de conocimiento de Yahveh, como cubren las aguas el mar. Aquel d\u00eda la ra\u00edz de Jes\u00e9 que estar\u00e1 enhiesta ser\u00e1 signo de los pueblos\u201d. En la ant\u00edfona escuchamos que este nuevo rey ser\u00e1 signo para las naciones; ante \u00e9l callar\u00e1n los reyes, y la gente ir\u00e1 a rezarle. Aqu\u00ed tenemos una referencia al cap\u00edtulo 52 del Libro del profeta Isa\u00edas, al \u201cCuarto c\u00e1ntico del Siervo\u201d: \u201cAnte \u00e9l cerrar\u00e1n los reyes la boca, pues ver\u00e1n lo que nunca se les cont\u00f3, y reconocer\u00e1n lo que nunca oyeron\u201d. El profeta en su \u201cC\u00e1ntico\u201d nos presenta al Siervo de Dios, que sufrir\u00e1, pero no ser\u00e1 un sufrir por sufrir. En completa obediencia a Dios, el Siervo har\u00e1 de su vida una ofrenda gratificante por los pecadores de muchas otras gentes. Los anuncios del Libro de Isa\u00edas encuentran su cumplimiento en la persona de Jesucristo. \u00c9l es el descendiente de David, esto nos lo muestran dos evangelistas: Lucas y Mateo. Ambos escriben la genealog\u00eda de Jes\u00fas, genealog\u00eda en que podemos encontrar tanto al rey David, como a Jes\u00e9, su padre, como antepasado de nuestro Maestro de Nazaret. En Jes\u00fas descans\u00f3 el Esp\u00edritu del Se\u00f1or, \u00c9l es signo de salvaci\u00f3n para las naciones, ante \u00c9l callan los reyes, pues ver\u00e1n Su pasi\u00f3n, una ofrenda propiciatoria por nuestros pecados. Algo inimaginable, un Dios loco de amor por el hombre entrega su vida por \u00e9l en la cruz. En esta ant\u00edfona se nos muestra el mayor sentido de la Encarnaci\u00f3n de Dios: Jes\u00fas viene para ser nuestro rey. Pero su reino no es est\u00e1 marcado por honores terrenales, por la riqueza o por un poder humano ilimitado. Su reino es, ante todo, servicio: servicio para los hombres, servicio que le conduce al \u00e1rbol de la cruz. En este sufrimiento, en esta muerte, entrega su vida, para aunar a la humanidad con Dios. Su muerte traer\u00e1 Redenci\u00f3n para todos: \u00a1Qu\u00e9 buena informaci\u00f3n para nosotros! Todos estamos invitados que acoger el don de Dios, la Redenci\u00f3n de Dios, para ir por la vida tras los pasos de nuestro Maestro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Saludos en Cristo! 19 de diciembre y una nueva Gran Ant\u00edfona de Adviento ante nosotros para reflexionar. Escuch\u00e9mosla de la voz del p. Tomasz Jarosz. La ant\u00edfona de hoy es una gran llamada al Mes\u00edas, el cual ha de venir y liberar al ser humano, y nos remite a dos fragmentos del Libro del profeta [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3628,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[57],"tags":[],"class_list":["post-3691","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-clamando-al-mesias"],"acf":[],"_links":{"self":[{"href":"https:\/\/forworld.redemptor.pl\/es\/wp-json\/wp\/v2\/posts\/3691"}],"collection":[{"href":"https:\/\/forworld.redemptor.pl\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/forworld.redemptor.pl\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/forworld.redemptor.pl\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/forworld.redemptor.pl\/es\/wp-json\/wp\/v2\/comments?post=3691"}],"version-history":[{"count":1,"href":"https:\/\/forworld.redemptor.pl\/es\/wp-json\/wp\/v2\/posts\/3691\/revisions"}],"predecessor-version":[{"id":3692,"href":"https:\/\/forworld.redemptor.pl\/es\/wp-json\/wp\/v2\/posts\/3691\/revisions\/3692"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/forworld.redemptor.pl\/es\/wp-json\/wp\/v2\/media\/3628"}],"wp:attachment":[{"href":"https:\/\/forworld.redemptor.pl\/es\/wp-json\/wp\/v2\/media?parent=3691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/forworld.redemptor.pl\/es\/wp-json\/wp\/v2\/categories?post=3691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/forworld.redemptor.pl\/es\/wp-json\/wp\/v2\/tags?post=3691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}